{"id":4049,"date":"2019-03-13T13:16:57","date_gmt":"2019-03-13T13:16:57","guid":{"rendered":"http:\/\/www.domotrade.com\/hijasdesanjose\/?post_type=fw-portfolio&#038;p=4049"},"modified":"2020-09-05T21:21:20","modified_gmt":"2020-09-05T21:21:20","slug":"te-seguiremos","status":"publish","type":"fw-portfolio","link":"https:\/\/hijasdesanjose.org\/en\/project\/te-seguiremos\/","title":{"rendered":"Te seguiremos"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<p class=\"has-text-color has-very-dark-gray-color wp-block-paragraph\">Tras tus pasos, en camino,<br \/>\naprendiendo en la marcha,<br \/>\nen comunidad itinerante,<br \/>\nte seguiremos, Se\u00f1or.<\/p>\n\n\n<p class=\"has-text-color has-very-dark-gray-color wp-block-paragraph\">Porque T\u00fa tienes palabras de vida<br \/>\nque llegan al coraz\u00f3n<br \/>\ny descubren nuevos rumbos.<\/p>\n\n\n<p class=\"has-text-color has-very-dark-gray-color wp-block-paragraph\">Porque T\u00fa nos miras a los ojos,<br \/>\nnos muestras tu rostro<br \/>\ny nos invitas a nuevos horizontes.<\/p>\n\n\n<p class=\"has-text-color has-very-dark-gray-color wp-block-paragraph\">Porque T\u00fa sacudes nuestros pies,<br \/>\nquebrando nuestras rutinas<br \/>\ny nos lanzas a nuevos desaf\u00edos.<\/p>\n\n\n<p class=\"has-text-color has-very-dark-gray-color wp-block-paragraph\">Porque T\u00fa eres el Se\u00f1or,<br \/>\nla Fuente de la Vida<br \/>\ny nos llamas a una nueva existencia.<\/p>\n\n\n<p class=\"has-text-color has-very-dark-gray-color wp-block-paragraph\">S\u00ed, Se\u00f1or, te seguiremos,<br \/>\npara sembrar tu Palabra,<br \/>\npara alumbrar la Esperanza,<br \/>\npara construir el Reino.<\/p>\n\n\n<p class=\"has-text-color has-very-dark-gray-color wp-block-paragraph\">Te seguiremos,<br \/>\ndejando lo que sea necesario,<br \/>\nsin atarnos a los bienes,<br \/>\nni a los afectos,<br \/>\nni a nuestros propios proyectos.<br \/>\nLo dejaremos todo, Se\u00f1or,<br \/>\npara que ocupes el centro<br \/>\ny el horizonte<br \/>\ny empapes nuestra sed de encuentro.<\/p>\n\n\n<p class=\"has-text-color has-very-dark-gray-color wp-block-paragraph\">Abre, Se\u00f1or, tus brazos<br \/>\ny estr\u00e9chanos fuerte,<br \/>\nsostennos en las dificultades<br \/>\ny anima nuestro esp\u00edritu<br \/>\nen los conflictos.<br \/>\nS\u00ed, queremos seguirte, ser disc\u00edpulos,<br \/>\necos de tus palabras,<br \/>\nreflejos de tu mirada,<br \/>\ntestigos de tu presencia.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Tras tus pasos, en camino, aprendiendo en la marcha, en comunidad itinerante, te seguiremos, Se\u00f1or. Porque T\u00fa tienes palabras&hellip;<\/p>\n","protected":false},"featured_media":4362,"comment_status":"closed","ping_status":"closed","template":"","class_list":["post-4049","fw-portfolio","type-fw-portfolio","status-publish","has-post-thumbnail","hentry","fw-portfolio-category-orar"],"_links":{"self":[{"href":"https:\/\/hijasdesanjose.org\/en\/wp-json\/wp\/v2\/fw-portfolio\/4049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hijasdesanjose.org\/en\/wp-json\/wp\/v2\/fw-portfolio"}],"about":[{"href":"https:\/\/hijasdesanjose.org\/en\/wp-json\/wp\/v2\/types\/fw-portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/hijasdesanjose.org\/en\/wp-json\/wp\/v2\/comments?post=4049"}],"version-history":[{"count":3,"href":"https:\/\/hijasdesanjose.org\/en\/wp-json\/wp\/v2\/fw-portfolio\/4049\/revisions"}],"predecessor-version":[{"id":12481,"href":"https:\/\/hijasdesanjose.org\/en\/wp-json\/wp\/v2\/fw-portfolio\/4049\/revisions\/12481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hijasdesanjose.org\/en\/wp-json\/wp\/v2\/media\/4362"}],"wp:attachment":[{"href":"https:\/\/hijasdesanjose.org\/en\/wp-json\/wp\/v2\/media?parent=4049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}